{"id":5780,"date":"2023-02-15T15:32:49","date_gmt":"2023-02-15T20:32:49","guid":{"rendered":"https:\/\/ibiom.com\/equipement-medical-specialise\/equipement-medical-pour-hopitaux\/equipement-medical-pour-oncologie-copy\/"},"modified":"2023-02-16T10:48:33","modified_gmt":"2023-02-16T15:48:33","slug":"equipement-medical-pour-chimiotherapie","status":"publish","type":"page","link":"https:\/\/ibiom.com\/fr\/equipement-medical-specialise\/equipement-medical-pour-hopitaux\/equipement-medical-pour-chimiotherapie\/","title":{"rendered":"\u00c9quipement m\u00e9dical pour chimioth\u00e9rapie"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=\u00a0\u00bb.vc_custom_1586880251014{padding-top: 60px !important;padding-bottom: 60px !important;}\u00a0\u00bb][vc_column][vc_custom_heading text=\u00a0\u00bb\u00c9quipement m\u00e9dical pour chimioth\u00e9rapie\u00a0\u00bb font_container=\u00a0\u00bbtag:h1|text_align:center\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>La chimioth\u00e9rapie<\/strong><\/p>\n<p>[\/vc_column_text][vc_row_inner content_placement=\u00a0\u00bbmiddle\u00a0\u00bb gap=\u00a0\u00bb20&Prime; css=\u00a0\u00bb.vc_custom_1609969039436{padding-top: 20px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">La chimioth\u00e9rapie est un traitement m\u00e9dical utilis\u00e9 contre plusieurs types de cancers. Bien que certaines formes de chimioth\u00e9rapie puissent \u00eatre effectu\u00e9es \u00e0 domicile, la majorit\u00e9 des traitements ont lieu dans les centres de canc\u00e9rologie, dans les h\u00f4pitaux et dans les cliniques m\u00e9dicales. La plupart des s\u00e9ances de chimioth\u00e9rapie sont effectu\u00e9es en soins ambulatoires, c\u2019est-\u00e0-dire que le patient visite l\u2019h\u00f4pital ou la clinique pour recevoir son traitement et retourne \u00e0 la maison le jour m\u00eame.<\/p>\n<p style=\"text-align: justify;\">Toutefois, pour les s\u00e9ances de tr\u00e8s longue dur\u00e9e, le patient est hospitalis\u00e9. En effet, la dur\u00e9e d\u2019une s\u00e9ance de chimioth\u00e9rapie varie d\u2019un patient \u00e0 l\u2019autre, pouvant aller d\u2019une dizaine de minutes \u00e0 plus de 24\u00a0heures. Lors de l\u2019administration de ces traitements, les professionnels de la sant\u00e9 ont recours \u00e0 de l\u2019\u00e9quipement m\u00e9dical sp\u00e9cialis\u00e9 pour la chimioth\u00e9rapie. Cet \u00e9quipement se compose d\u2019appareils m\u00e9dicaux et de mat\u00e9riel m\u00e9dical, comme des gants et des lunettes de protection, ainsi que de mobilier m\u00e9dical, comme des fauteuils de traitement.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Pour assurer \u00e0 la fois le confort des patients et celui des professionnels de la sant\u00e9, il est important que l\u2019\u00e9quipement m\u00e9dical utilis\u00e9 pour la chimioth\u00e9rapie soit ergonomique et facilement ajustable.<\/p>\n<\/blockquote>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb5782&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676562388825{padding-left: 20px !important;}\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676300469791{padding-bottom: 40px !important;background-color: #16425d !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_custom_heading text=\u00a0\u00bbVous cherchez une marque d&rsquo;\u00e9quipement m\u00e9dical?\u00a0\u00bb font_container=\u00a0\u00bbtag:h3|font_size:22px|text_align:left|color:%23ffffff\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbIBIOM distribue l\u2019\u00e9quipement de plusieurs marques reconnues pour leur qualit\u00e9 et leur ergonomie, dont ergoCentric et Allseating.\u00a0\u00bb font_container=\u00a0\u00bbtag:p|font_size:16px|text_align:left|color:%23ffffff|line_height:20px\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676392686969{margin-top: -10px !important;}\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_btn title=\u00a0\u00bbEn savoir plus\u00a0\u00bb style=\u00a0\u00bbclassic\u00a0\u00bb shape=\u00a0\u00bbsquare\u00a0\u00bb color=\u00a0\u00bbwhite\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676392700558{margin-bottom: 0px !important;}\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Fibiom.com%2Ffr%2Fmarques-equipement-medical%2F\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1675893084301{padding-top: 60px !important;padding-bottom: 60px !important;}\u00a0\u00bb][vc_column][vc_row_inner equal_height=\u00a0\u00bbyes\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb gap=\u00a0\u00bb20&Prime; css=\u00a0\u00bb.vc_custom_1676301700228{padding-top: 30px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb1\/12&Prime;][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb4\/12&Prime;][vc_single_image image=\u00a0\u00bb5777&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/ibiom.com\/fr\/produits\/fauteuil-de-traitement-triad\/\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbFauteuil de traitement TRIAD\u00a0\u00bb font_container=\u00a0\u00bbtag:h2|font_size:20px|text_align:center\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Fibiom.com%2Ffr%2Fproduits%2Ffauteuil-de-traitement-triad%2F|title:Fauteuil%20de%20traitement%20TRIAD\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/12&Prime;][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_custom_heading text=\u00a0\u00bb\u00c9quipement m\u00e9dical pour chimioth\u00e9rapie : les fauteuils de traitement\u00a0\u00bb font_container=\u00a0\u00bbtag:h2|font_size:26px|text_align:left|line_height:17px\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Les fauteuils de traitement font partie de l\u2019\u00e9quipement m\u00e9dical fr\u00e9quemment utilis\u00e9 en chimioth\u00e9rapie. Lors d\u2019une s\u00e9ance de chimioth\u00e9rapie, le patient est appel\u00e9 \u00e0 passer de nombreuses heures en position assise. C\u2019est pourquoi il est important de lui fournir un fauteuil qui lui procure un confort pour toute la dur\u00e9e du traitement. Par exemple, plusieurs fauteuils de traitement sont dot\u00e9s de coussins rembourr\u00e9s procurant un support lombaire ad\u00e9quat ou d\u2019un repose-pied ajustable facilitant le soulagement des crampes. De telles caract\u00e9ristiques aident \u00e0 pr\u00e9venir la fatigue excessive et les douleurs chez le patient. De plus, pour que le patient puisse s\u2019occuper pendant son traitement ou pour qu\u2019il puisse avoir acc\u00e8s facilement \u00e0 ses effets personnels, les fauteuils de traitement peuvent \u00eatre munis d\u2019une table d\u2019appoint. Celle-ci est souvent pivotante ou enti\u00e8rement amovible pour ne pas encombrer le patient lorsqu\u2019il ne souhaite pas l\u2019utiliser.<\/p>\n<p style=\"text-align: justify;\">Si le confort du patient est un \u00e9l\u00e9ment essentiel duquel tenir compte lors du choix d\u2019un fauteuil de traitement, il ne faut pas pour autant n\u00e9gliger le confort des professionnels de la sant\u00e9. Car ils interagissent quotidiennement avec cet \u00e9quipement m\u00e9dical. Ainsi, les fauteuils de traitement offrent aussi diff\u00e9rentes fonctionnalit\u00e9s qui ont pour but de faciliter le travail du personnel m\u00e9dical et de pr\u00e9venir les blessures professionnelles. Par exemple, les fauteuils de traitement peuvent \u00eatre dot\u00e9s de roues et de poign\u00e9es de transport pour en faciliter le d\u00e9placement. De plus, pour \u00e9viter que le personnel m\u00e9dical n\u2019ait \u00e0 forcer excessivement lors de l\u2019installation du patient, certains fauteuils de traitement sont munis de m\u00e9canismes \u00e9lectriques qui permettent d\u2019ajuster la hauteur ou l\u2019inclinaison du fauteuil. Bref, il est important que les fauteuils de traitement utilis\u00e9s en chimioth\u00e9rapie offrent des fonctionnalit\u00e9s qui assurent autant le confort du patient que celui du personnel m\u00e9dical. Le fauteuil de traitement TRIAD est un exemple d\u2019\u00e9quipement m\u00e9dical pour chimioth\u00e9rapie qui r\u00e9pond \u00e0 ces crit\u00e8res.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb equal_height=\u00a0\u00bbyes\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676301138522{padding-right: 10px !important;padding-left: 10px !important;background-image: url(https:\/\/ibiom.com\/wp-content\/uploads\/2023-02-13_09-56-17-scaled.jpg?id=5595) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; offset=\u00a0\u00bbvc_hidden-xs\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; offset=\u00a0\u00bbvc_hidden-xs\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbVous avez des besoins sp\u00e9cifiques?\u00a0\u00bb font_container=\u00a0\u00bbtag:h3|font_size:22px|text_align:left|color:%23ffffff\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbNotre \u00e9quipe de professionnels, chez Ibiom, est l\u00e0 pour vous conseiller et vous orienter<br \/>\nvers la gamme de produits la plus adapt\u00e9e \u00e0 vos besoins.\u00a0\u00bb font_container=\u00a0\u00bbtag:p|font_size:16px|text_align:left|color:%23ffffff|line_height:20px\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676300432749{margin-top: -10px !important;}\u00a0\u00bb][vc_btn title=\u00a0\u00bbPrendre contact\u00a0\u00bb shape=\u00a0\u00bbsquare\u00a0\u00bb color=\u00a0\u00bbwhite\u00a0\u00bb align=\u00a0\u00bbleft\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676300994328{margin-bottom: 0px !important;}\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Fibiom.com%2Ffr%2Fcontactez-nous%2F\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb60px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb equal_height=\u00a0\u00bbyes\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676300968637{background-color: #f4f4f4 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; offset=\u00a0\u00bbvc_hidden-lg vc_hidden-md vc_hidden-sm\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; offset=\u00a0\u00bbvc_hidden-lg vc_hidden-md vc_hidden-sm\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbVous avez des besoins sp\u00e9cifiques?\u00a0\u00bb font_container=\u00a0\u00bbtag:h3|font_size:22px|text_align:left|color:%23000000&Prime; use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbNotre \u00e9quipe de professionnels, chez Ibiom, est l\u00e0 pour vous conseiller et vous orienter vers la gamme de produits la plus adapt\u00e9e \u00e0 vos besoins.\u00a0\u00bb font_container=\u00a0\u00bbtag:p|font_size:16px|text_align:left|color:%23000000|line_height:20px\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676301190964{margin-top: -10px !important;}\u00a0\u00bb][vc_btn title=\u00a0\u00bbPrendre contact\u00a0\u00bb style=\u00a0\u00bbclassic\u00a0\u00bb shape=\u00a0\u00bbsquare\u00a0\u00bb color=\u00a0\u00bbblack\u00a0\u00bb align=\u00a0\u00bbleft\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676300910718{margin-bottom: 0px !important;}\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Fibiom.com%2Ffr%2Fcontactez-nous%2F\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb60px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676476518645{padding-top: 60px !important;padding-bottom: 80px !important;}\u00a0\u00bb][vc_column][vc_row_inner equal_height=\u00a0\u00bbyes\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb gap=\u00a0\u00bb20&Prime; css=\u00a0\u00bb.vc_custom_1676301700228{padding-top: 30px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_custom_heading text=\u00a0\u00bbLe fauteuil de traitement TRIAD pour la chimioth\u00e9rapie\u00a0\u00bb font_container=\u00a0\u00bbtag:h2|font_size:26px|text_align:left|line_height:17px\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Le fauteuil de traitement TRIAD est un \u00e9quipement m\u00e9dical recommand\u00e9 pour la chimioth\u00e9rapie. Ce fauteuil a \u00e9t\u00e9 con\u00e7u sp\u00e9cialement pour les traitements n\u00e9cessitant que le patient maintienne une position assise sur de longues p\u00e9riodes. Il offre donc plusieurs caract\u00e9ristiques ax\u00e9es sur le confort du patient. Par exemple, les coussins du fauteuil TRIAD offrent un excellent support lombaire. Ils n\u2019ont aucune couture, ce qui aide \u00e0 r\u00e9duire les points de pression et permet un meilleur contr\u00f4le des infections. Le fauteuil de traitement TRIAD est aussi muni d\u2019un repose-pied \u00e0 r\u00e9glage \u00e9lectrique, qui permet au patient de soulager lui-m\u00eame ses crampes aux jambes. Les accoudoirs sont synchronis\u00e9s au dossier pour offrir davantage de confort au patient, et ils pivotent vers l\u2019int\u00e9rieur pour accommoder les patients de plus petite taille. Il est int\u00e9ressant de noter que le fauteuil TRIAD a \u00e9t\u00e9 cr\u00e9\u00e9 en collaboration avec des experts en positionnement. Cela a permis de concevoir un fauteuil m\u00e9dical qui favorise le maintien d\u2019une posture ergonomique pour toute la dur\u00e9e du traitement. Plusieurs autres caract\u00e9ristiques font que les patients appr\u00e9cient le fauteuil de traitement TRIAD pendant une s\u00e9ance de chimioth\u00e9rapie. Par exemple, il est possible d\u2019y ajouter une table pivotante amovible, pouvant \u00eatre plac\u00e9e sur le c\u00f4t\u00e9 gauche ou le c\u00f4t\u00e9 droit du fauteuil. Pour les patients qui souhaitent rester en mouvement pendant le traitement, un v\u00e9lo d\u2019exercice miniature peut \u00eatre install\u00e9 sur le repose-pied. Bref, le fauteuil de traitement TRIAD est dot\u00e9 de nombreuses fonctionnalit\u00e9s qui assurent le confort du patient tout au long d\u2019une s\u00e9ance de chimioth\u00e9rapie.<\/p>\n<p style=\"text-align: justify;\">Le fauteuil de traitement TRIAD propose \u00e9galement plusieurs fonctionnalit\u00e9s qui visent \u00e0 optimiser le travail du personnel m\u00e9dical et \u00e0 r\u00e9duire les risques de blessures professionnelles. Par exemple, le fauteuil offre plusieurs options de r\u00e9glage \u00e9lectrique (hauteur du fauteuil, inclinaison des jambes, inclinaison du dossier, etc.). Celles-ci sont contr\u00f4l\u00e9es au moyen d\u2019un interrupteur \u00e0 main facile \u00e0 utiliser. Pour faciliter l\u2019acc\u00e8s au patient, les accoudoirs du fauteuil se soul\u00e8vent, s\u2019inclinent et pivotent vers l\u2019ext\u00e9rieur. Ils peuvent aussi \u00eatre enti\u00e8rement retir\u00e9s. Pour assurer un d\u00e9placement simple et rapide, le fauteuil TRIAD est muni de quatre roues doubles de 5\u00a0po et de poign\u00e9es de transport fix\u00e9es \u00e0 l\u2019arri\u00e8re du dossier. Les roues sont verrouillables afin de maintenir le fauteuil en place de fa\u00e7on s\u00e9curitaire. Les p\u00e9dales de frein sont facilement accessibles, puisqu\u2019il y en a une sur chaque roue, et il suffit d\u2019en activer une seule pour bloquer les quatre roues. Un espace libre de 13\u00a0cm est \u00e9galement pr\u00e9vu sous la structure du fauteuil pour l\u2019utilisation d\u2019un l\u00e8ve-personne ou d\u2019une table d\u2019appoint. Toutes ces fonctionnalit\u00e9s facilitent le travail du personnel m\u00e9dical et aident \u00e0 r\u00e9duire les tensions musculaires lors de la manipulation du fauteuil et de l\u2019installation du patient. C\u2019est pourquoi le fauteuil de traitement TRIAD est un \u00e9quipement m\u00e9dical recommand\u00e9 pour la chimioth\u00e9rapie. Il convient \u00e9galement \u00e0 d\u2019autres applications m\u00e9dicales, comme la n\u00e9phrologie et la dialyse.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/12&Prime;][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb4\/12&Prime;][vc_single_image image=\u00a0\u00bb5687&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/ibiom.com\/fr\/produits\/fauteuil-de-traitement-triad\/\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbFauteuil de traitement TRIAD\u00a0\u00bb font_container=\u00a0\u00bbtag:h2|font_size:20px|text_align:center\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Fibiom.com%2Ffr%2Fproduits%2Ffauteuil-de-traitement-triad%2F|title:Fauteuil%20de%20traitement%20TRIAD\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/12&Prime;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676392594660{padding-bottom: 40px !important;background-color: #f4f4f4 !important;}\u00a0\u00bb][vc_column][vc_custom_heading text=\u00a0\u00bbVous voulez en savoir plus sur les caract\u00e9risques de nos \u00e9quipements m\u00e9dicaux?\u00a0\u00bb font_container=\u00a0\u00bbtag:h3|font_size:26px|text_align:center|line_height:25px\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbConsultez notre blog pour en apprendre davantage!\u00a0\u00bb font_container=\u00a0\u00bbtag:p|font_size:16px|text_align:center|color:%23000000|line_height:20px\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1676392840488{margin-top: -10px !important;}\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb20px\u00a0\u00bb][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/12&Prime;][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb5\/6&Prime;][vc_masonry_grid post_type=\u00a0\u00bbpost\u00a0\u00bb max_items=\u00a0\u00bb3&Prime; gap=\u00a0\u00bb35&Prime; orderby=\u00a0\u00bbrand\u00a0\u00bb item=\u00a0\u00bbbasicGrid_FadeInWithSideContent\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1676562465021-4b25b642-9b7b-8&Prime; taxonomies=\u00a0\u00bb186&Prime;][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/12&Prime;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1675893084301{padding-top: 60px !important;padding-bottom: 60px !important;}\u00a0\u00bb][vc_column][vc_row_inner equal_height=\u00a0\u00bbyes\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb gap=\u00a0\u00bb20&Prime; css=\u00a0\u00bb.vc_custom_1676301700228{padding-top: 30px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_custom_heading text=\u00a0\u00bbAutres \u00e9quipements m\u00e9dicaux pour chimioth\u00e9rapie\u00a0\u00bb font_container=\u00a0\u00bbtag:h2|font_size:26px|text_align:left|line_height:17px\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Plusieurs autres \u00e9quipements m\u00e9dicaux sont utilis\u00e9s dans les \u00e9tablissements de soins de sant\u00e9 offrant des traitements de chimioth\u00e9rapie. Par exemple, il existe d\u2019autres mod\u00e8les de fauteuils de traitement, comme le fauteuil inclinable pour patient Foster ou le fauteuil INO. Ces fauteuils polyvalents sont aussi souvent utilis\u00e9s dans les r\u00e9sidences pour personnes \u00e2g\u00e9es et dans les \u00e9tablissements de soins de longue dur\u00e9e. Certains h\u00f4pitaux utilisent \u00e9galement des tables de traitement, qui peuvent servir pour la chimioth\u00e9rapie ainsi que pour plusieurs autres traitements et examens m\u00e9dicaux. <strong><a href=\"https:\/\/ibiom.com\/fr\/produits-categories\/tables-de-traitement-dechographie-et-dechocardiographie\/\">Les tables de traitement ECHO-FLEX<\/a><\/strong> comptent parmi les \u00e9quipements m\u00e9dicaux recommand\u00e9s pour les h\u00f4pitaux et les autres \u00e9tablissements de soins de sant\u00e9.<\/p>\n<p style=\"text-align: justify;\">De plus, \u00e0 l\u2019occasion, les patients recevant un traitement de chimioth\u00e9rapie sont accompagn\u00e9s d\u2019un conjoint, d\u2019un parent ou d\u2019un ami. Les h\u00f4pitaux et les cliniques m\u00e9dicales doivent pr\u00e9voir des si\u00e8ges pour ces visiteurs. <strong><a href=\"https:\/\/ibiom.com\/fr\/produits-categories\/fauteuils-de-traitement\/\">Les fauteuils Foster<\/a><\/strong> sont un exemple de mobilier qui convient \u00e0 une utilisation dans le secteur m\u00e9dical. Ils sont confortables, robustes et faciles \u00e0 nettoyer. En ce qui concerne les tables et les bureaux de travail pour le personnel m\u00e9dical, plusieurs \u00e9tablissements de soins optent pour des postes d\u2019accueil ajustables en hauteur et des postes de travail portatifs, comme le <strong><a href=\"https:\/\/ibiom.com\/fr\/produits\/poste-de-travail-portatif\/\">poste de travail mobile \u00e0 hauteur r\u00e9glable upCentric<\/a><\/strong>. Le mobilier r\u00e9glable en hauteur est recommand\u00e9 aupr\u00e8s des professionnels de la sant\u00e9. Celui-ci favorise le maintien d\u2019une posture ergonomique tout au long de la journ\u00e9e et il r\u00e9duit la fatigue associ\u00e9e au maintien d\u2019une position statique.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/4&Prime;][vc_single_image image=\u00a0\u00bb5750&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/ibiom.com\/fr\/produits\/tables-de-traitement-echo-flex-5002\/\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbTable de traitement ECHO-FLEX 5002&Prime; font_container=\u00a0\u00bbtag:h2|font_size:20px|text_align:center\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Fibiom.com%2Ffr%2Fproduits%2Ftables-de-traitement-echo-flex-5002%2F|title:Table%20de%20traitement%20ECHO-FLEX%205002&Prime;][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/4&Prime;][vc_single_image image=\u00a0\u00bb5685&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/ibiom.com\/fr\/produits\/civiere-echo-flex-4400-do\/\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbTable de traitement ECHO-FLEX 4400-DO\u00a0\u00bb font_container=\u00a0\u00bbtag:h2|font_size:20px|text_align:center\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Fibiom.com%2Ffr%2Fproduits%2Fciviere-echo-flex-4400-do%2F|title:Table%20de%20traitement%20ECHO-FLEX%204400-DO\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=\u00a0\u00bb.vc_custom_1586880251014{padding-top: 60px !important;padding-bottom: 60px !important;}\u00a0\u00bb][vc_column][vc_custom_heading text=\u00a0\u00bb\u00c9quipement m\u00e9dical pour chimioth\u00e9rapie\u00a0\u00bb [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":5715,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5780","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9quipement m\u00e9dical pour chimioth\u00e9rapie | Fauteuils de traitement<\/title>\n<meta name=\"description\" content=\"L\u2019\u00e9quipement m\u00e9dical utilis\u00e9 en chimioth\u00e9rapie inclut des fauteuils de traitement, dont le fauteuil TRIAD, con\u00e7u pour le confort du patient et du personnel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibiom.com\/fr\/equipement-medical-specialise\/equipement-medical-pour-hopitaux\/equipement-medical-pour-chimiotherapie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9quipement m\u00e9dical pour chimioth\u00e9rapie | Fauteuils de traitement\" \/>\n<meta property=\"og:description\" content=\"L\u2019\u00e9quipement m\u00e9dical utilis\u00e9 en chimioth\u00e9rapie inclut des fauteuils de traitement, dont le fauteuil TRIAD, con\u00e7u pour le confort du patient et du personnel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibiom.com\/fr\/equipement-medical-specialise\/equipement-medical-pour-hopitaux\/equipement-medical-pour-chimiotherapie\/\" \/>\n<meta property=\"og:site_name\" content=\"Ibiom\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-16T15:48:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibiom.com\/wp-content\/uploads\/poison-chimiotherapie-cancer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/ibiom.com\/wp-content\/uploads\/poison-chimiotherapie-cancer.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/equipement-medical-specialise\\\/equipement-medical-pour-hopitaux\\\/equipement-medical-pour-chimiotherapie\\\/\",\"url\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/equipement-medical-specialise\\\/equipement-medical-pour-hopitaux\\\/equipement-medical-pour-chimiotherapie\\\/\",\"name\":\"\u00c9quipement m\u00e9dical pour chimioth\u00e9rapie | Fauteuils de traitement\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/#website\"},\"datePublished\":\"2023-02-15T20:32:49+00:00\",\"dateModified\":\"2023-02-16T15:48:33+00:00\",\"description\":\"L\u2019\u00e9quipement m\u00e9dical utilis\u00e9 en chimioth\u00e9rapie inclut des fauteuils de traitement, dont le fauteuil TRIAD, con\u00e7u pour le confort du patient et du personnel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/equipement-medical-specialise\\\/equipement-medical-pour-hopitaux\\\/equipement-medical-pour-chimiotherapie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibiom.com\\\/fr\\\/equipement-medical-specialise\\\/equipement-medical-pour-hopitaux\\\/equipement-medical-pour-chimiotherapie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/equipement-medical-specialise\\\/equipement-medical-pour-hopitaux\\\/equipement-medical-pour-chimiotherapie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9quipement sp\u00e9cialis\u00e9\",\"item\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/equipement-medical-specialise\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9quipement m\u00e9dical pour h\u00f4pitaux\",\"item\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/equipement-medical-specialise\\\/equipement-medical-pour-hopitaux\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00c9quipement m\u00e9dical pour chimioth\u00e9rapie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/\",\"name\":\"Ibiom\",\"description\":\"Ibiom\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/#organization\",\"name\":\"Ibiom\",\"alternateName\":\"Medical equipment\",\"url\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibiom.com\\\/wp-content\\\/uploads\\\/1655753135954.jpg\",\"contentUrl\":\"https:\\\/\\\/ibiom.com\\\/wp-content\\\/uploads\\\/1655753135954.jpg\",\"width\":800,\"height\":193,\"caption\":\"Ibiom\"},\"image\":{\"@id\":\"https:\\\/\\\/ibiom.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9quipement m\u00e9dical pour chimioth\u00e9rapie | Fauteuils de traitement","description":"L\u2019\u00e9quipement m\u00e9dical utilis\u00e9 en chimioth\u00e9rapie inclut des fauteuils de traitement, dont le fauteuil TRIAD, con\u00e7u pour le confort du patient et du personnel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibiom.com\/fr\/equipement-medical-specialise\/equipement-medical-pour-hopitaux\/equipement-medical-pour-chimiotherapie\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9quipement m\u00e9dical pour chimioth\u00e9rapie | Fauteuils de traitement","og_description":"L\u2019\u00e9quipement m\u00e9dical utilis\u00e9 en chimioth\u00e9rapie inclut des fauteuils de traitement, dont le fauteuil TRIAD, con\u00e7u pour le confort du patient et du personnel.","og_url":"https:\/\/ibiom.com\/fr\/equipement-medical-specialise\/equipement-medical-pour-hopitaux\/equipement-medical-pour-chimiotherapie\/","og_site_name":"Ibiom","article_modified_time":"2023-02-16T15:48:33+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/ibiom.com\/wp-content\/uploads\/poison-chimiotherapie-cancer.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/ibiom.com\/wp-content\/uploads\/poison-chimiotherapie-cancer.jpg","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibiom.com\/fr\/equipement-medical-specialise\/equipement-medical-pour-hopitaux\/equipement-medical-pour-chimiotherapie\/","url":"https:\/\/ibiom.com\/fr\/equipement-medical-specialise\/equipement-medical-pour-hopitaux\/equipement-medical-pour-chimiotherapie\/","name":"\u00c9quipement m\u00e9dical pour chimioth\u00e9rapie | Fauteuils de traitement","isPartOf":{"@id":"https:\/\/ibiom.com\/fr\/#website"},"datePublished":"2023-02-15T20:32:49+00:00","dateModified":"2023-02-16T15:48:33+00:00","description":"L\u2019\u00e9quipement m\u00e9dical utilis\u00e9 en chimioth\u00e9rapie inclut des fauteuils de traitement, dont le fauteuil TRIAD, con\u00e7u pour le confort du patient et du personnel.","breadcrumb":{"@id":"https:\/\/ibiom.com\/fr\/equipement-medical-specialise\/equipement-medical-pour-hopitaux\/equipement-medical-pour-chimiotherapie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibiom.com\/fr\/equipement-medical-specialise\/equipement-medical-pour-hopitaux\/equipement-medical-pour-chimiotherapie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibiom.com\/fr\/equipement-medical-specialise\/equipement-medical-pour-hopitaux\/equipement-medical-pour-chimiotherapie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibiom.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9quipement sp\u00e9cialis\u00e9","item":"https:\/\/ibiom.com\/fr\/equipement-medical-specialise\/"},{"@type":"ListItem","position":3,"name":"\u00c9quipement m\u00e9dical pour h\u00f4pitaux","item":"https:\/\/ibiom.com\/fr\/equipement-medical-specialise\/equipement-medical-pour-hopitaux\/"},{"@type":"ListItem","position":4,"name":"\u00c9quipement m\u00e9dical pour chimioth\u00e9rapie"}]},{"@type":"WebSite","@id":"https:\/\/ibiom.com\/fr\/#website","url":"https:\/\/ibiom.com\/fr\/","name":"Ibiom","description":"Ibiom","publisher":{"@id":"https:\/\/ibiom.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibiom.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ibiom.com\/fr\/#organization","name":"Ibiom","alternateName":"Medical equipment","url":"https:\/\/ibiom.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ibiom.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ibiom.com\/wp-content\/uploads\/1655753135954.jpg","contentUrl":"https:\/\/ibiom.com\/wp-content\/uploads\/1655753135954.jpg","width":800,"height":193,"caption":"Ibiom"},"image":{"@id":"https:\/\/ibiom.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ibiom.com\/fr\/wp-json\/wp\/v2\/pages\/5780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibiom.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ibiom.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ibiom.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ibiom.com\/fr\/wp-json\/wp\/v2\/comments?post=5780"}],"version-history":[{"count":0,"href":"https:\/\/ibiom.com\/fr\/wp-json\/wp\/v2\/pages\/5780\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/ibiom.com\/fr\/wp-json\/wp\/v2\/pages\/5715"}],"wp:attachment":[{"href":"https:\/\/ibiom.com\/fr\/wp-json\/wp\/v2\/media?parent=5780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}